{"id":14019,"date":"2025-02-27T19:11:51","date_gmt":"2025-02-27T19:11:51","guid":{"rendered":"https:\/\/thooft.bast-agency.com\/?post_type=collecties&#038;p=14019"},"modified":"2025-02-27T19:11:51","modified_gmt":"2025-02-27T19:11:51","slug":"chaise-dours-tete-a-tete-droite","status":"publish","type":"collecties","link":"https:\/\/thooft.com\/fr\/collections\/chaise-dours-tete-a-tete-droite\/","title":{"rendered":"Chaise d'ours T\u00eate-\u00e0-t\u00eate - droite"},"content":{"rendered":"<p>2 chaises Bear avec table d'appoint. Elles sont dispos\u00e9es l'une \u00e0 c\u00f4t\u00e9 de l'autre, ce qui est id\u00e9al pour les placer contre un mur droit.<\/p>","protected":false},"excerpt":{"rendered":"<p>2 chaises Bear avec table d'appoint. Elles sont dispos\u00e9es l'une \u00e0 c\u00f4t\u00e9 de l'autre, ce qui est id\u00e9al pour les placer contre un mur droit.<\/p>","protected":false},"featured_media":14020,"menu_order":0,"template":"","format":"standard","meta":{"footnotes":""},"type-collectie":[98],"soort":[60],"merk":[63],"class_list":["post-14019","collecties","type-collecties","status-publish","format-standard","has-post-thumbnail","hentry","type-collectie-stoelen","soort-klassieke-tuinmeubelen","merk-bear-chair"],"_links":{"self":[{"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/collecties\/14019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/collecties"}],"about":[{"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/types\/collecties"}],"version-history":[{"count":0,"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/collecties\/14019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/media\/14020"}],"wp:attachment":[{"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/media?parent=14019"}],"wp:term":[{"taxonomy":"type-collectie","embeddable":true,"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/type-collectie?post=14019"},{"taxonomy":"soort","embeddable":true,"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/soort?post=14019"},{"taxonomy":"merk","embeddable":true,"href":"https:\/\/thooft.com\/fr\/wp-json\/wp\/v2\/merk?post=14019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}